{"id":4084,"date":"2023-09-06T21:50:50","date_gmt":"2023-09-06T19:50:50","guid":{"rendered":"http:\/\/www.ams-ag.de\/?page_id=4084"},"modified":"2024-11-02T01:03:03","modified_gmt":"2024-11-02T00:03:03","slug":"gros-appareil","status":"publish","type":"page","link":"https:\/\/www.ams-ag.de\/fr\/produkte\/heimbedarf\/grossgeraet\/","title":{"rendered":"Gros appareil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4084\" class=\"elementor elementor-4084\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e757f90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e757f90\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7aa4de9\" data-id=\"7aa4de9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2018f66 elementor-widget elementor-widget-image\" data-id=\"2018f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"614\" height=\"600\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2024\/01\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe.jpg\" class=\"attachment-medium_large size-medium_large wp-image-14133\" alt=\"\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2024\/01\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe.jpg 614w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2024\/01\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe-300x293.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2024\/01\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe-12x12.jpg 12w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1bd8c3d\" data-id=\"1bd8c3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abd207b elementor-widget elementor-widget-heading\" data-id=\"abd207b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Gro\u00dfger\u00e4t f\u00fcr den Heimbedarf<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7775d79 elementor-widget elementor-widget-heading\" data-id=\"7775d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">MEDISEND\u00aesuper<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-238511d elementor-widget elementor-widget-text-editor\" data-id=\"238511d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDas MEDISEND\u00aesuper ist die Standardausf\u00fchrung unserer MEDISEND\u00aesuper-Reihe. Es wird sowohl von Therapeuten als auch im privaten Bereich genutzt.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2152fca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2152fca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6030d53\" data-id=\"6030d53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac7d431 elementor-widget elementor-widget-heading\" data-id=\"ac7d431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schnelle Auswahl<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d81e8e1 elementor-widget elementor-widget-text-editor\" data-id=\"d81e8e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWenn Sie mit der Anwendung des MEDISEND\u00aesuper-Ger\u00e4tes schon vertraut sind, klicken Sie einfach auf den Link zum Produkt:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b7bfa elementor-widget elementor-widget-button\" data-id=\"b0b7bfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e32242 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e32242\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2e1dd1\" data-id=\"f2e1dd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65b4460 elementor-widget elementor-widget-heading\" data-id=\"65b4460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inhalt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54e0f94 elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"54e0f94\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Bio\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Magnetfeldtherapie und Bioresonanz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Einfuehrung\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einf\u00fchrung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#anrufen\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einfach anrufen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Anwendung\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anwendung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Frequenzen\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frequenzen und Testverfahren<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Tensorkurs\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tensorkurs<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Dauer\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dauer der Anwendung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Informationsuebertragung\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Informations\u00fcbertragung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Anwendungsablauf\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anwendungsablauf<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Einstellungen\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einstellungen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Applikatoren\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Applikatoren<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Eigenschaften\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ger\u00e4teeigenschaften<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Zubehoer\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Zubeh\u00f6r<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bed65c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bed65c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-053803e\" data-id=\"053803e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1232ac elementor-widget elementor-widget-menu-anchor\" data-id=\"c1232ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Bio\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4143d13 elementor-widget elementor-widget-heading\" data-id=\"4143d13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Magnetfeldtherapie und Bioresonanz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd61919 elementor-widget elementor-widget-text-editor\" data-id=\"bd61919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie sind auf der Suche nach einem\u00a0Magnetfeld- und Bioresonanzger\u00e4t f\u00fcr zu Hause, dessen Eigenschaften \u00fcber die eines Kleinger\u00e4tes hinausgehen? Dann haben Sie die richtige Seite aufgerufen.<\/p><p>Unser\u00a0MEDISEND\u00aesuper\u00a0ist ein leicht zu bedienendes Magnetfeld- und Bioresonanzger\u00e4t, das h\u00e4ufig in Praxen eingesetzt wird. Sie k\u00f6nnen es jedoch auch ganz einfach\u00a0zu Hause anwenden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56a7e51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56a7e51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-420a27d\" data-id=\"420a27d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9eb073d elementor-widget elementor-widget-menu-anchor\" data-id=\"9eb073d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Einfuehrung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2d419 elementor-widget elementor-widget-heading\" data-id=\"3d2d419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ausf\u00fchrliche Einf\u00fchrung zum Gro\u00dfger\u00e4t<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7475d5b elementor-widget elementor-widget-text-editor\" data-id=\"7475d5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Magnetfeldger\u00e4te? MEDISEND\u00aesuper? Wie nutzt man die \u00fcberhaupt?<\/p>\n<p>Wenn Sie sich zun\u00e4chst ganz allgemein \u00fcber die Anwendung des MEDISEND\u00aesuper-Ger\u00e4tes informieren m\u00f6chten, lesen Sie die ausf\u00fchrliche Einf\u00fchrung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06f2b68 elementor-widget elementor-widget-heading\" data-id=\"06f2b68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Magnetfeldger\u00e4t f\u00fcr zu Hause<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8844d07 elementor-widget elementor-widget-text-editor\" data-id=\"8844d07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit unserem\u00a0MEDISEND\u00aesuper bieten wir Ihnen ein einfach zu bedienendes Gro\u00dfger\u00e4t, mit dem Sie im allt\u00e4glichen Gebrauch die Magnetfeldtherapie und die Bioresonanz anwenden k\u00f6nnen.<\/p><p>Das MEDISEND\u00aesuper bietet eine weitaus\u00a0gr\u00f6\u00dfere Frequenzbandbreite als jedes unserer Kleinger\u00e4te. Die Frequenzauswahl geht von 0,1 &#8211; 1000 Hz.<\/p><p>Lesen Sie nachfolgend, wie das MEDISEND\u00aesuper grunds\u00e4tzlich genutzt und eingesetzt wird. F\u00fcr die individuellen Beschreibungen und Details zu dem Ger\u00e4t, lesen Sie bitte die\u00a0spezifischen Informationen auf der Produktseite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4efa040 elementor-widget elementor-widget-button\" data-id=\"4efa040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f9dffa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f9dffa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fd5722\" data-id=\"7fd5722\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88bb42c elementor-widget elementor-widget-menu-anchor\" data-id=\"88bb42c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"anrufen\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50dc2d5 elementor-widget elementor-widget-heading\" data-id=\"50dc2d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einfach anrufen!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e8cadb elementor-widget elementor-widget-text-editor\" data-id=\"5e8cadb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vielleicht m\u00f6chten Sie es sich viel einfacher machen. Haben Sie bitte keine Scheu, uns anzurufen. Schildern Sie uns, warum Sie sich f\u00fcr ein Magnetfeldger\u00e4t interessieren oder stellen Sie uns Ihre Fragen zu den einzelnen Ger\u00e4ten. Wir helfen Ihnen, das oder die Ger\u00e4te zu finden, die f\u00fcr Sie in Frage kommen. Anschlie\u00dfend k\u00f6nnen Sie in Ruhe die dazugeh\u00f6rigen Produktbeschreibungen lesen.<\/p><p>Wir werden Sie niemals ungewollt kontaktieren oder Ihre Kontaktdaten an Dritte weitergeben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9570f3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b9570f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c5bab elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b8c5bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Advanced Medical Systems GmbH (AMS)<\/strong><br \/>Hauptstra\u00dfe 26<br \/>D-97990 Weikersheim<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c523b38 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c523b38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Telefon: <a href=\"tel:+4979349934890\" target=\"_blank\" rel=\"noopener\"><b>+49 7934 993489-0<\/b><\/a><br \/>Telefax: +49 7934 993489-44<br \/>E-Mail: <a class=\"mail\" title=\"Opens window for sending email\" href=\"mailto:info@ams-ag.de\"><b>info@ams-ag.de<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1651fcd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1651fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Gesch\u00e4ftszeiten:<br \/><\/b>Montag-Donnerstag 8:00-17:00 Uhr CET<br \/>Freitag 8:00-14:30 Uhr CET<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9926c1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d9926c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce35be0 elementor-align-left elementor-widget__width-auto elementor-widget-tablet__width-inherit elementor-widget elementor-widget-button\" data-id=\"ce35be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/rueckruftermin\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00fcckruftermin<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c6d04 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"35c6d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/info-material\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Info-Material bestellen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea065e elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"0ea065e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/login-beantragen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Login beantragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c625ce elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"4c625ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/newsletter-abonnieren\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Newsletter abonnieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b1d175 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b1d175\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aca4990\" data-id=\"aca4990\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36f457c elementor-widget elementor-widget-menu-anchor\" data-id=\"36f457c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Anwendung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f0b7ad elementor-widget elementor-widget-heading\" data-id=\"2f0b7ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf8b05d elementor-widget elementor-widget-heading\" data-id=\"bf8b05d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einsatz<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bcffa8 elementor-widget elementor-widget-text-editor\" data-id=\"3bcffa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Magnetfeldtherapie und Bioresonanz werden eingesetzt, um die\u00a0Regulationsf\u00e4higkeit des K\u00f6rpers zu unterst\u00fctzen. Das bedeutet, dass es keine Indikation gibt, f\u00fcr die die Anwendung besser oder schlechter geeignet ist als f\u00fcr andere.<\/p><p>Wenn Sie sich \u00fcber die allgemeine Anwendung der Magnetfeldtherapie informieren m\u00f6chten, lesen Sie bitte die Rubrik Magnetfeldtherapie und Bioinformative Medizin.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/\"><b>Magnetfeldtherapie und Bioinformative Medizin<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32646cd elementor-widget elementor-widget-heading\" data-id=\"32646cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anwendung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c92f4e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c92f4e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-998de57\" data-id=\"998de57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca2d4ae elementor-widget elementor-widget-text-editor\" data-id=\"ca2d4ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jedes MEDISEND\u00aesuper Ger\u00e4t kann ein pulsierendes Magnetfeld mit einer Frequenz zwischen 0,1 &#8211; 1000 Hz abgeben. Um das elektromagnetische Feld auf den Organismus zu \u00fcbertragen, wird an die MEDISEND\u00aesuper Ger\u00e4te ein Applikator angeschlossen:<\/p><p>Die\u00a0<a href=\"http:\/\/ams-onlineshop.de\/produkt\/magneto-schlaufe\/\" target=\"_blank\" rel=\"noopener\"><b>MAGNETO-Schlaufe<\/b><\/a>\u00a0oder der\u00a0<a href=\"http:\/\/ams-onlineshop.de\/produkt\/magneto-ring\/\" target=\"_blank\" rel=\"noopener\"><b>MAGNETO-Ring<\/b><\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e16325 elementor-widget elementor-widget-text-editor\" data-id=\"4e16325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie Beschreibung der Anwendung erfolgt mit folgenden Komponenten:\n<ul>\n \t<li>Das MEDISEND\u00aesuper<\/li>\n \t<li>mit der MAGNETO-Schlaufe,<\/li>\n \t<li>mit dem MEDICUP<\/li>\n \t<li>und einem Paar Handelektroden.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1839fe9\" data-id=\"1839fe9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f72ed75 elementor-widget elementor-widget-image\" data-id=\"f72ed75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"293\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe__Handelektroden_und_Medicup-1-300x293.jpg\" class=\"attachment-medium size-medium wp-image-4103\" alt=\"AMS Medisend super mit Magneto-Schlaufe, Handelektroden und Medicup\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe__Handelektroden_und_Medicup-1-300x293.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medisend_super_mit_Magneto-Schlaufe__Handelektroden_und_Medicup-1.jpg 614w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-44202b6 elementor-widget elementor-widget-text-editor\" data-id=\"44202b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Die Anwendung ist sehr einfach:<\/b><br \/>Sie stellen mittels des Drehknopfes am MEDISEND\u00aesuper die gew\u00fcnschte Frequenz ein und starten das Ger\u00e4t. Die auf der rechten Seite angeschlossene MAGNETO-Schlaufe wird zur \u00dcbertragung des pulsierenden Magnetfeldes auf oder neben den K\u00f6rper gelegt.<\/p><p>Der physiologische Wirkungskreis reicht bis zu 1 m im Durchmesser. Das von der Schlaufe abgegebene Feld ist weder sicht- noch h\u00f6rbar. Sehr sensible Menschen sp\u00fcren manchmal etwas &#8211; das muss aber nicht sein. Auch wenn das Magnetfeld des eingeschalteten Ger\u00e4tes nicht sofort ersp\u00fcrbar ist, erf\u00fcllt es dennoch seinen Zweck.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d594dd elementor-widget elementor-widget-button\" data-id=\"6d594dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9131fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9131fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2236ca0\" data-id=\"2236ca0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3fef6a elementor-widget elementor-widget-menu-anchor\" data-id=\"e3fef6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Frequenzen\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d18ea4 elementor-widget elementor-widget-heading\" data-id=\"0d18ea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequenzen und Testverfahren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df73b86 elementor-widget elementor-widget-heading\" data-id=\"df73b86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Welche Frequenz soll ich w\u00e4hlen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6519a4 elementor-widget elementor-widget-text-editor\" data-id=\"f6519a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das MEDISEND\u00aesuper verf\u00fcgt nicht \u00fcber voreingestellte Programme. Die Frequenzauswahl erfolgt \u00fcber den seitlichen Drehknopf. Dabei steht Ihnen die komplette Frequenz-Bandbreite zwischen 0,1 &#8211; 1000 Hz zur Verf\u00fcgung.<\/p><p>Grunds\u00e4tzlich k\u00f6nnen alle Frequenzen daf\u00fcr geeignet sein, die Regulation des K\u00f6rpers positiv zu beeinflussen.<\/p><p>Es gibt Empfehlungen, f\u00fcr unterschiedliche Situationen ausgew\u00e4hlte Frequenzen anzuwenden. Erfahrungsgem\u00e4\u00df k\u00f6nnen einigen Frequenzen bestimmte Eigenschaften zugeordnet werden. Hier einige Beispiele:<\/p><ul><li>ausgleichend (7,8 Hz)<\/li><li>anregend (33 \/ 20 Hz)<\/li><li>beruhigend (3,0 \/ 4,0 Hz)<\/li><li>konzentrationsf\u00f6rdernd (7,8 \/ 8,2 Hz)<\/li><li>entspannend (3,0 Hz \/ 1,2 Hz)<\/li><li>wohltuend bei Elektrosensibilit\u00e4t (1,2 Hz)<\/li><\/ul><p>In der Gebrauchsanweisung f\u00fcr das MEDISEND\u00aesuper befindet sich auch eine Liste, in der\u00a0Erfahrungswerte\u00a0unterschiedlicher Anwender zusammengetragen wurden. Diese Liste hilft Ihnen, einen Einstieg in die Nutzung der unterschiedlichen Frequenzen zu finden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cb796a elementor-widget elementor-widget-heading\" data-id=\"7cb796a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Testverfahren<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a9c19c elementor-widget elementor-widget-text-editor\" data-id=\"6a9c19c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tObwohl die Liste sicherlich eine gute Hilfestellung darstellt, ist es ratsam, ein\u00a0Testverfahren zu beherrschen, um individuell austesten zu k\u00f6nnen, welche Frequenz sich f\u00fcr die gew\u00fcnschte Anwendung am besten eignet.\n\nHierf\u00fcr k\u00f6nnen Sie das Testverfahren ausw\u00e4hlen, das Ihnen am meisten liegt.\n\nDie meistgenutzten Testmethoden\u00a0sind:\n<ul>\n \t<li>Tensor<\/li>\n \t<li>Kinesiologie<\/li>\n \t<li>EAV (Elektroakupunktur nach Dr. Voll)<\/li>\n \t<li>RAC (Reflex Auriculo Cardiaque &#8211; ein Pulsreflex Test)<\/li>\n<\/ul>\nUm die\u00a0geeignete Frequenz auszutesten gehen Sie so vor, wie Sie mit der gew\u00e4hlten Testmethode z.B. auch ein hom\u00f6opathisches Mittel austesten w\u00fcrden.\n\nStellen Sie die auszutestende Frequenz am MEDISEND\u00aesuper ein und starten Sie das Ger\u00e4t. Sobald die Frequenz durch die MAGNETO-Schlaufe abgegeben wird und sich der zu testende Organismus im Wirkungskreis befindet,\u00a0\u00fcberpr\u00fcfen Sie mit Ihrer Testmethode die Reaktion. Sobald Sie ein positives Testergebnis erhalten, haben Sie eine passende Frequenz\u00a0 zur Anwendung gefunden.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05071f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05071f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf41a65\" data-id=\"bf41a65\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0dc6ead elementor-widget elementor-widget-menu-anchor\" data-id=\"0dc6ead\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Tensorkurs\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27aa075 elementor-widget elementor-widget-heading\" data-id=\"27aa075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tensorkurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecae833 elementor-widget elementor-widget-text-editor\" data-id=\"ecae833\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEs gibt unterschiedliche M\u00f6glichkeiten und Ausbildungen, um\u00a0Methoden zur Testung\u00a0kennen- und anwenden zu lernen. Die AMS bietet ein bis zwei Mal im Jahr einen\u00a0Tensorkurs an, in dem Sie die Handhabung und Nutzung des Tensors in Theorie und mit praktischen \u00dcbungen erlernen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58090c2 elementor-widget elementor-widget-wp-widget-tribe-widget-events-list\" data-id=\"58090c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-tribe-widget-events-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"tribe-compatibility-container\" >\n\t<div\n\t\t class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" \t\tdata-js=\"tribe-events-view\"\n\t\tdata-view-rest-url=\"https:\/\/www.ams-ag.de\/fr\/wp-json\/tribe\/views\/v2\/html\"\n\t\tdata-view-manage-url=\"1\"\n\t\t\t\t\t\t\tdata-view-breakpoint-pointer=\"4600451d-8334-42e0-9e5d-5127a7d48004\"\n\t\t\t>\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Prochains \\u00c9v\\u00e8nements mis en avant \\u2013 AMS \\u2013 Advanced Medical Systems\",\"limit\":\"5\",\"no_upcoming_events\":false,\"featured_events_only\":true,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Titre\\u00a0:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-REPLACE_TO_ID-title\",\"name\":\"widget-tribe-widget-events-list[REPLACE_TO_ID][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Afficher\\u00a0:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-REPLACE_TO_ID-limit\",\"name\":\"widget-tribe-widget-events-list[REPLACE_TO_ID][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"no_upcoming_events\":{\"label\":\"Cacher ce widget s\\u2019il n\\u2019y a pas d\\u2019\\u00e9v\\u00e8nements \\u00e0 venir.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-REPLACE_TO_ID-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[REPLACE_TO_ID][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Limiter uniquement pour les \\u00e9v\\u00e8nements mis en avant\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-REPLACE_TO_ID-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[REPLACE_TO_ID][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"G\\u00e9n\\u00e9rer les donn\\u00e9es JSON-LD\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-REPLACE_TO_ID-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[REPLACE_TO_ID][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"events\":[],\"url\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\\\/?post_type=tribe_events&eventDisplay=widget-events-list&featured=1\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-07-15 00:00:00\",\"now\":\"2026-07-15 06:24:12\",\"home_url\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\",\"rest_url\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\\\/?post_type=tribe_events&eventDisplay=widget-events-list&featured=1&rest_route=%2Fwp%2Fv2%2Fpages%2F4084\",\"today_title\":\"Cliquer pour s\\u00e9lectionner la date du jour\",\"today_label\":\"Aujourd\\u2019hui\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"d\\\/m\\\/Y\",\"month_and_year_compact\":\"m\\\/Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" | \"},\"messages\":{\"notice\":[\"Il n\\u2019y a pas d\\u2019\\u00e9v\\u00e8nements \\u00e0 venir.\"]},\"start_of_week\":\"1\",\"header_title\":\"Mis en avant\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":true,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;featured=1&#038;ical=1\",\"text\":\"Exporter \\u00c9v\\u00e8nements\",\"title\":\"Utilisez ceci pour partager les donn\\u00e9es de calendrier avec Google Calendar, Apple iCal et d\\u2019autres applications compatibles\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"4600451d-8334-42e0-9e5d-5127a7d48004\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\\\/events\\\/liste\\\/(\\\/?:featured|hervorgehoben)\\\/\",\"view_label\":\"Liste\",\"aria_label\":\"Display \\u00c9v\\u00e8nements in Liste View\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Voir le calendrier\",\"view_more_title\":\"Voir plus d\\u2019\\u00e9v\\u00e8nements.\",\"view_more_link\":\"https:\\\/\\\/www.ams-ag.de\\\/fr\\\/events\\\/\",\"widget_title\":\"Anstehende Veranstaltungen\",\"hide_if_no_upcoming_events\":false,\"display\":[],\"subscribe_links\":{\"gcal\":{\"label\":\"Google Agenda\",\"single_label\":\"Ajouter \\u00e0 Google Agenda\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Ajouter \\u00e0 iCalendar\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\"Exporter le fichier .ics\",\"single_label\":\"Exporter le fichier .ics\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exporter le fichier Outlook .ics\",\"single_label\":\"Exporter le fichier Outlook .ics\",\"visible\":true,\"block_slug\":null}},\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tAnstehende Veranstaltungen\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div  class=\"tribe-events-header__messages tribe-events-c-messages tribe-common-b2\"  >\n\t\t\t<div class=\"tribe-events-c-messages__message tribe-events-c-messages__message--notice\" tabindex=\"0\" role=\"alert\" aria-live=\"assertive\">\n\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--messages-not-found tribe-events-c-messages__message-icon-svg\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 21 23\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<g fill-rule=\"evenodd\">\n\t\t<path d=\"M.5 2.5h20v20H.5z\"\/>\n\t\t<path stroke-linecap=\"round\" d=\"M7.583 11.583l5.834 5.834m0-5.834l-5.834 5.834\" class=\"tribe-common-c-svgicon__svg-stroke\"\/>\n\t\t<path stroke-linecap=\"round\" d=\"M4.5.5v4m12-4v4\"\/>\n\t\t<path stroke-linecap=\"square\" d=\"M.5 7.5h20\"\/>\n\t<\/g>\n<\/svg>\n<span class=\"tribe-common-a11y-visual-hide\">\n\tNotice<\/span>\n\t\t\t\t\t\t\t<div\n\t\t\t\t\t data-key=\"0\" >\n\t\t\t\t\tIl n\u2019y a pas d\u2019\u00e9v\u00e8nements \u00e0 venir.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js='tribe-events-view-nonce-data' type='application\/json'>{\"tvn1\":\"234be85f10\",\"tvn2\":\"\"}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0665d98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0665d98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11dc52a\" data-id=\"11dc52a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc40fd elementor-widget elementor-widget-menu-anchor\" data-id=\"cbc40fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Dauer\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3cf2f elementor-widget elementor-widget-heading\" data-id=\"4c3cf2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dauer der Anwendung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0e2da elementor-widget elementor-widget-text-editor\" data-id=\"1f0e2da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie k\u00f6nnen die Anwendung mit\u00a0einer oder mehreren Frequenzen durchf\u00fchren. Meist werden pro Anwendung ein bis zwei Frequenzen nacheinander genutzt.<\/p><p>F\u00fcr die Anwendung wird die MAGNETO-Schlaufe einfach\u00a0auf oder neben den K\u00f6rper gelegt.<\/p><p>\u00dcblicherweise dauert eine Anwendung\u00a0ca. 15 Minuten. Dies ist jedoch nur ein Richtwert &#8211; es kann durchaus sowohl eine l\u00e4ngere als auch eine k\u00fcrzere Anwendungsdauer gew\u00e4hlt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffec413 elementor-widget elementor-widget-button\" data-id=\"ffec413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4694995 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4694995\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8d718a\" data-id=\"e8d718a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-373f706 elementor-widget elementor-widget-menu-anchor\" data-id=\"373f706\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Informationsuebertragung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c3636e elementor-widget elementor-widget-heading\" data-id=\"8c3636e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcbertragung von Bioinformationen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee1678 elementor-widget elementor-widget-heading\" data-id=\"7ee1678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Exogene Informations\u00fcbertragung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6898aa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6898aa6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-198ea45\" data-id=\"198ea45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3760c4 elementor-widget elementor-widget-text-editor\" data-id=\"d3760c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tJede elektromagnetische Welle ist in der Lage,\u00a0Informationen zu transportieren und zu \u00fcbertragen. Somit k\u00f6nnen Sie w\u00e4hrend der Anwendung des MEDISEND\u00aesuper-Ger\u00e4tes Substrate wie z.B. hom\u00f6opathische Mittel, Bachbl\u00fcten und viel mehr mit dem pulsierenden Magnetfeld \u00fcbertragen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a10ea35 elementor-widget elementor-widget-text-editor\" data-id=\"a10ea35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUm sich diese Eigenschaft zunutze zu machen, k\u00f6nnen Sie optional einen Becher &#8211; unseren\u00a0MEDICUP\u00a0&#8211; an das MEDISEND\u00aesuper anschlie\u00dfen. Alle Substrate, die Sie in den Becher stellen, werden als\u00a0zus\u00e4tzliche Information\u00a0mit dem pulsierenden elektromagnetischen Feld auf den Organismus \u00fcbertragen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72f5e0c\" data-id=\"72f5e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6919628 elementor-widget elementor-widget-image\" data-id=\"6919628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"293\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medicup_klein-300x293.jpg\" class=\"attachment-medium size-medium wp-image-4111\" alt=\"AMS Medicup\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medicup_klein-300x293.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medicup_klein.jpg 614w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-607f840 elementor-widget elementor-widget-text-editor\" data-id=\"607f840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die \u00dcbertragung der Informationen ist unabh\u00e4ngig davon, welche Frequenz Sie w\u00e4hlen:<\/p><p>Jede Frequenz ist Tr\u00e4gerwelle und kann zum Einschwingen \/ \u00dcbertragen eingesetzt werden.<\/p><p>Was es genau mit dem Einschwingen von Substraten und Informationen auf sich hat, lesen Sie im Men\u00fcpunkt Substrat\u00fcbertragung.<\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/substratuebertragung\/\" rel=\"noopener\"><strong>Substrat\u00fcbertragung<\/strong><\/a><\/p><p>Wie auch schon bei der Auswahl der Frequenz ist es ebenso bei der Auswahl der zu \u00fcbertragenden Substrate ratsam, die Mittel vorher durch ein geeignetes Testverfahren auszutesten. Auch hier eignen sich wie bereits erw\u00e4hnt besonders Tensor, Kinesiologie, die EAV oder das RAC-Testverfahren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33b4da3 elementor-widget elementor-widget-heading\" data-id=\"33b4da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Endogene Informations\u00fcbertragung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d4bca36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4bca36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-6b1c1a7\" data-id=\"6b1c1a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d1b3ba elementor-widget elementor-widget-text-editor\" data-id=\"6d1b3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDas MEDISEND\u00aesuper bietet nicht nur die M\u00f6glichkeit der exogenen Informations\u00fcbertragung. Dar\u00fcber hinaus k\u00f6nnen mit Hilfe von angeschlossenen Handelektroden auch\u00a0endogene, also k\u00f6rpereigene Information\u00a0auf das pulsierende Magnetfeld \u00fcbertragen werden.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d0629ba\" data-id=\"d0629ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6462a9b elementor-widget elementor-widget-image\" data-id=\"6462a9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Handelektroden_nebeneinander-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4112\" alt=\"AMS Handelektroden nebeneinander\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a9703b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a9703b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-a657689\" data-id=\"a657689\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-124d93b elementor-widget elementor-widget-text-editor\" data-id=\"124d93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGemeinsam mit dem MEDICUP werden die Handelektroden auf der linken Seite des Ger\u00e4tes angeschlossen. W\u00e4hrend der Anwendung werden die Handelektroden\u00a0in beiden H\u00e4nden\u00a0gehalten oder anderweitig\u00a0symmetrisch mit der Haut in Kontakt gebracht (z.B. unter die Kniekehlen geschoben).\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3721d50\" data-id=\"3721d50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d70447 elementor-widget elementor-widget-image\" data-id=\"1d70447\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Medisend_super_mit_Handelektroden_und_Medicup-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4113\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-85e4909 elementor-widget elementor-widget-text-editor\" data-id=\"85e4909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>H\u00e4ufig werden wir gefragt, ob der K\u00f6rper \u00fcber die Handelektroden Informationen bekommt. Doch das ist nicht der Fall.\u00a0Im Gegenteil:\u00a0Die Handelektroden dienen dazu, die Informationen des\u00a0kompletten K\u00f6rper-Biofeldes aufzunehmen. Diese aufgenommen Informationen werden auf das von der Schlaufe abgegebene Magnetfeld moduliert und somit wieder an den K\u00f6rper\u00a0zur\u00fcck gegeben.<\/p><p>Das bedeutet, dass der K\u00f6rper w\u00e4hrend der Anwendung seine eigenen Informationen von au\u00dfen &#8222;gezeigt bekommt&#8220;. Durch dieses\u00a0Aufmerksamkeitssignal kann die Regulation auf individuelle Weise unterst\u00fctzt werden.<\/p><p>Die Handelektroden k\u00f6nnen Sie wie auch den MEDICUP optional als Zubeh\u00f6r kaufen.<b><\/b><\/p><p><a href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/geraetezubehoer\/\" target=\"_blank\" rel=\"noopener\"><b>Zubeh\u00f6r<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d496519 elementor-widget elementor-widget-button\" data-id=\"d496519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6ffb74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6ffb74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6a120e\" data-id=\"c6a120e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b313d47 elementor-widget elementor-widget-menu-anchor\" data-id=\"b313d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Anwendungsablauf\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc53cc8 elementor-widget elementor-widget-heading\" data-id=\"dc53cc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendungsablauf auf einen Blick:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1590b5 elementor-widget elementor-widget-text-editor\" data-id=\"b1590b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li>Geeignete Frequenz zur Anwendung durch Auswahl aus der\u00a0Liste und\/oder ein individuelles Testverfahren\u00a0ausw\u00e4hlen<\/li>\n \t<li>Gegebenenfalls\u00a0Mittel zur \u00dcbertragung\u00a0ausw\u00e4hlen bzw. austesten (Hom\u00f6opathika, Bachbl\u00fcten, Sch\u00fcssler Salze, Nosoden und andere Pr\u00e4parate, Phytotherapeutika usw.)<\/li>\n \t<li>Mittel (z.B. in Ampullenform) in den MEDICUP stellen<\/li>\n \t<li>Handelektroden\u00a0symmetrisch\u00a0nutzen<\/li>\n \t<li>MAGNETO-Schlaufe\u00a0auf oder neben den K\u00f6rper\u00a0platzieren und das Ger\u00e4t mit der gew\u00fcnschten Frequenz des Magnetfeldes starten<\/li>\n \t<li>Anwendungszeit\u00a0ca. 15 Minuten<\/li>\n \t<li>Nach der Anwendung\u00a0viel klares Wasser trinken, um die Ausleitung und Reinigung zu unterst\u00fctzen<\/li>\n \t<li>Die Anwendungen k\u00f6nnen 1-2x w\u00f6chentlich wiederholt werden &#8211; auch eine t\u00e4gliche Anwendung (besonders im Akutfall) kann durchgef\u00fchrt werden.\u00a0Eine \u00dcberdosierung ist nicht m\u00f6glich.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82fe775 elementor-widget elementor-widget-button\" data-id=\"82fe775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23ceb1b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23ceb1b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0f456d\" data-id=\"e0f456d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a2b09d elementor-widget elementor-widget-menu-anchor\" data-id=\"8a2b09d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Einstellungen\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-893debb elementor-widget elementor-widget-heading\" data-id=\"893debb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einstellungsm\u00f6glichkeiten und mehr<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddc0fdb elementor-widget elementor-widget-heading\" data-id=\"ddc0fdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Festfrequenz \/ Frequenzdurchlauf<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ea3a09 elementor-widget elementor-widget-text-editor\" data-id=\"1ea3a09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDas MEDISEND\u00aesuper bietet neben den\u00a0w\u00e4hlbaren Festfrequenzen\u00a0zwischen 0,1 und 1000 Hz auch die Option, einen\u00a0Frequenzdurchlauf\u00a0einzustellen. Sie haben die Auswahl zwischen folgenden Frequenzdurchl\u00e4ufen:\n<ul>\n \t<li>100 &#8211; 1 Hz<\/li>\n \t<li>1000 &#8211; 1 Hz<\/li>\n<\/ul>\nDie Frequenzdurchl\u00e4ufe werden h\u00e4ufig zur\u00a0Unterst\u00fctzung von ausleitenden Verfahren\u00a0gew\u00e4hlt oder als\u00a0Einstieg in einen Anwendungszyklus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c93184 elementor-widget elementor-widget-heading\" data-id=\"9c93184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Generator<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-572d99e elementor-widget elementor-widget-text-editor\" data-id=\"572d99e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDas MEDISEND\u00aesuper verf\u00fcgt \u00fcber\u00a0einen Magnetfeldgenerator, der die gew\u00fcnschte Frequenz abgibt.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a34c50c elementor-widget elementor-widget-heading\" data-id=\"a34c50c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Modulation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc084c elementor-widget elementor-widget-text-editor\" data-id=\"6dc084c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDas MEDISEND\u00aesuper bietet die M\u00f6glichkeit, das Magnetfeld\u00a0im F\u00fcnfsekundentakt zu unterbrechen. Dies gibt der Anwendung einen\u00a0tonisierenden Charakter.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01f3c6d elementor-widget elementor-widget-heading\" data-id=\"01f3c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Intensit\u00e4t<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa2864 elementor-widget elementor-widget-text-editor\" data-id=\"3fa2864\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie Magnetfeldintensit\u00e4t ist beim MEDISEND\u00aesuper zwischen\u00a0zwei Stufen w\u00e4hlbar.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32c8f5f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32c8f5f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c8139b\" data-id=\"6c8139b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9eae68f elementor-widget elementor-widget-menu-anchor\" data-id=\"9eae68f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Applikatoren\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f73585 elementor-widget elementor-widget-heading\" data-id=\"8f73585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Applikatoren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7392e0 elementor-widget elementor-widget-text-editor\" data-id=\"f7392e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAls\u00a0Standardapplikator\u00a0f\u00fcr das MEDISEND\u00aesuper hat sich die im Preis enthaltene\u00a0MAGNETO-Schlaufe\u00a0bestens bew\u00e4hrt. F\u00fcr die\u00a0Anwendung an Gro\u00dftieren\u00a0ist der\u00a0MAGNETO-Ring\u00a0besonders n\u00fctzlich.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6a864e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6a864e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b512e54\" data-id=\"b512e54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef8e690 elementor-widget elementor-widget-heading\" data-id=\"ef8e690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mehr<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3db9e11 elementor-widget elementor-widget-text-editor\" data-id=\"3db9e11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lesen Sie alle spezifischen Details \u00fcber das MEDISEND\u00aesuper hier:<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/produkte\/heimbedarf\/grossgeraet\/medisendsuper\/\"><b>MEDISEND\u00aesuper<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa85a9 elementor-widget elementor-widget-text-editor\" data-id=\"6aa85a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lesen Sie alle spezifischen Details \u00fcber die Applikatoren und das genannte Zubeh\u00f6r in den individuellen Produktbeschreibungen im SHOP:<b><\/b><\/p><p><a href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/geraetezubehoer\/\" target=\"_blank\" rel=\"noopener\"><b>Ger\u00e4tezubeh\u00f6r im SHOP<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feb9da0 elementor-widget elementor-widget-button\" data-id=\"feb9da0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-246010c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"246010c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8f5f1c\" data-id=\"d8f5f1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3ace22 elementor-widget elementor-widget-menu-anchor\" data-id=\"d3ace22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Eigenschaften\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c90c1b5 elementor-widget elementor-widget-heading\" data-id=\"c90c1b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ger\u00e4teeigenschaften<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32266e5 elementor-widget elementor-widget-heading\" data-id=\"32266e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die Ger\u00e4te von Dr. Ludwig<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c28ab elementor-widget elementor-widget-text-editor\" data-id=\"a3c28ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle unsere Ger\u00e4te sind mit der von Dr. Ludwig entwickelten Technologie ausgestattet. Ihm war es besonders wichtig, mit seinen Ger\u00e4ten ein Magnetfeld zu erzeugen, das der\u00a0ungest\u00f6rten Natur nachempfunden\u00a0ist &#8211; deshalb gilt f\u00fcr alle von Dr. Ludwig und in seinem Institut (weiter)entwickelten Magnetfeldger\u00e4te:<\/p><ul><li>Erzeugung bzw. m\u00f6gliche Wahl des Hauptwertes des\u00a0Schumannfrequenzspektrums (7,8 Hz)<\/li><li>Erzeugung der\u00a0Geomagnetfrequenzen<\/li><li>Erzeugung der\u00a0Solarfrequenzen\u00a0(bis auf das MEDISEND\u00ae, das MEDISEND\u00aeprotect und den CEPES\u00ae-Laser, bei denen man aufgrund der Geh\u00e4usegr\u00f6\u00dfe auf den Einbau des Solarfrequenzgenerators verzichtete)<\/li><\/ul><p>Die genaue Beschreibung f\u00fcr Schumann-, Geomagnet- und Solarfrequenzen finden Sie im Men\u00fcpunkt Umweltsignale.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/umweltsignale\/\" rel=\"noopener\"><b>Umweltsignale<\/b><\/a><\/p><p>Alle Ger\u00e4te erzeugen ein Signal, dessen Impulsform und Magnetfeldst\u00e4rke optimal auf den K\u00f6rper abgestimmt ist. Lesen Sie hierzu mehr im Men\u00fcpunkt Qualit\u00e4tsmerkmale.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/qualitaetsmerkmale\/\" rel=\"noopener\"><b>Qualit\u00e4tsmerkmale<\/b><\/a><\/p><p>Die von Dr. Ludwig entwickelten Ger\u00e4te erkennen Sie am Pfeilsymbol.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/pfeilsymbol\/\" rel=\"noopener\"><b>Pfeilsymbol<\/b><\/a><\/p><p>Das erste von Dr. Ludwig erschaffene Ger\u00e4t war vor \u00fcber 40 Jahren das heutige MEDISEND\u00ae &#8211; damals nat\u00fcrlich noch in einer anderen Ausf\u00fchrung.<\/p><p>Wie und warum Dr. Ludwig sein erstes Magnetfeldger\u00e4t baute und wie er nach und nach die unterschiedlichen Ger\u00e4te entwickelte und erweiterte lesen Sie im Men\u00fcpunkt &#8222;Geschichte unserer Ger\u00e4te&#8220;.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/geschichte-unserer-geraete\/\" rel=\"noopener\"><b>Geschichte unserer Ger\u00e4te<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d45a8bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d45a8bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28030ba\" data-id=\"28030ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-975cf42 elementor-widget elementor-widget-menu-anchor\" data-id=\"975cf42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Zubehoer\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e765f1 elementor-widget elementor-widget-heading\" data-id=\"3e765f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ger\u00e4tezubeh\u00f6r<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9c9966 elementor-widget elementor-widget-text-editor\" data-id=\"a9c9966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bitte schauen Sie sich die Ger\u00e4tezubeh\u00f6r und die Beschreibungen dazu im SHOP an. Sie werden hier nicht weiter erl\u00e4utert.<b><\/b><\/p><p><a href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/geraetezubehoer\/\" target=\"_blank\" rel=\"noopener\"><b>Ger\u00e4tezubeh\u00f6r im SHOP<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b78f6c6 elementor-widget elementor-widget-button\" data-id=\"b78f6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/grossgeraet\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef39afc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef39afc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf6c0e3\" data-id=\"bf6c0e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6dfe72 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"c6dfe72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/fr\/produkte\/heimbedarf\/grossgeraet\/medisendsuper\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00aesuper<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfger\u00e4t f\u00fcr den Heimbedarf MEDISEND\u00aesuper Das MEDISEND\u00aesuper ist die Standardausf\u00fchrung unserer MEDISEND\u00aesuper-Reihe. Es wird sowohl von Therapeuten als auch im privaten Bereich genutzt. Schnelle Auswahl Wenn Sie mit der Anwendung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4153,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pmpro_default_level":"","footnotes":""},"class_list":["post-4084","page","type-page","status-publish","hentry","pmpro-has-access"],"_links":{"self":[{"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/pages\/4084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/comments?post=4084"}],"version-history":[{"count":144,"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/pages\/4084\/revisions"}],"predecessor-version":[{"id":18646,"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/pages\/4084\/revisions\/18646"}],"up":[{"embeddable":true,"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/pages\/4153"}],"wp:attachment":[{"href":"https:\/\/www.ams-ag.de\/fr\/wp-json\/wp\/v2\/media?parent=4084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}