{"id":3995,"date":"2023-09-05T21:40:07","date_gmt":"2023-09-05T19:40:07","guid":{"rendered":"http:\/\/www.ams-ag.de\/?page_id=3995"},"modified":"2026-04-29T19:10:56","modified_gmt":"2026-04-29T17:10:56","slug":"pequenos-dispositivos","status":"publish","type":"page","link":"https:\/\/www.ams-ag.de\/es\/produkte\/heimbedarf\/kleingeraete\/","title":{"rendered":"Peque\u00f1os accesorios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3995\" class=\"elementor elementor-3995\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca288da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca288da\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aed9527\" data-id=\"aed9527\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14c337a elementor-widget elementor-widget-image\" data-id=\"14c337a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/heim_kleingeraete-768x576.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11919\" alt=\"AMS Kleinger\u00e4te\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/heim_kleingeraete-768x576.jpg 768w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/heim_kleingeraete-300x225.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/heim_kleingeraete.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f62754\" data-id=\"5f62754\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26c3262 elementor-widget elementor-widget-heading\" data-id=\"26c3262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\u00dcberall dabei<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39eb8a9 elementor-widget elementor-widget-heading\" data-id=\"39eb8a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Kleinger\u00e4te f\u00fcr den Heimbedarf<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83d7d09 elementor-widget elementor-widget-text-editor\" data-id=\"83d7d09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSie suchen ein kleines und handliches Magnetfeldger\u00e4t\u00a0f\u00fcr zu Hause und unterwegs? Dann sind Sie auf dieser Seite genau richtig. Finden Sie hier Ihr Magnetfeldger\u00e4t, Ihren treuen Begleiter auf Schritt und Tritt.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62386af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62386af\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ef89bb\" data-id=\"4ef89bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff24755 elementor-widget elementor-widget-heading\" data-id=\"ff24755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schnelle Auswahl<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4cebd elementor-widget elementor-widget-text-editor\" data-id=\"bb4cebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie mit der Anwendung von Magnetfeldger\u00e4ten schon vertraut sind und bereits wissen, welches Ger\u00e4t Sie n\u00e4her interessiert, klicken Sie einfach auf den Link, der Sie direkt in den Shop bringt, und finden Sie ihr Produkt:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3b59a0 elementor-widget elementor-widget-button\" data-id=\"c3b59a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/kleingeraete\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kleinger\u00e4te im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ce0691 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ce0691\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3551d8\" data-id=\"a3551d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c86b186 elementor-widget elementor-widget-heading\" data-id=\"c86b186\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inhalt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34950c3 elementor-icon-list--layout-inline elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"34950c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#90\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">90t\u00e4giges R\u00fcckgaberecht<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Einfuehrung\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einf\u00fchrung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Magnetfeldgeraete\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Magnetfeldger\u00e4te f\u00fcr zu Hause<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#anrufen\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einfach anrufen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Anwendung\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anwendung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#wo\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wo?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Frequenz\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frequenz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Substratuebertragung\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Substrat\u00fcbertragung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Eigenschaften\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Eigenschaften<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Vergleich\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vergleich<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Pfeil\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pfeilsymbol<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Downloads\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Downloads<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#Prospekte\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prospekte<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-601d0845 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"601d0845\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64b182ae\" data-id=\"64b182ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ba79efc elementor-widget elementor-widget-menu-anchor\" data-id=\"1ba79efc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"90\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e8d59c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e8d59c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-12dbce8b\" data-id=\"12dbce8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cf569c elementor-widget elementor-widget-image\" data-id=\"3cf569c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-1024x1024.jpg\" class=\"attachment-large size-large wp-image-19627\" alt=\"AMS 90 Tage R\u00fcckgaberecht, Stempel\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-1024x1024.jpg 1024w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-300x300.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-150x150.jpg 150w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-768x768.jpg 768w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-1536x1536.jpg 1536w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage-12x12.jpg 12w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/09\/AMS-90-Tage.jpg 1540w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1bab623d\" data-id=\"1bab623d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20760a1 elementor-widget elementor-widget-heading\" data-id=\"20760a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">90t\u00e4giges R\u00fcckgaberecht*<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5101bfa6 elementor-widget elementor-widget-text-editor\" data-id=\"5101bfa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beim Kauf eines unserer Kleinger\u00e4te haben Sie ein 90t\u00e4giges R\u00fcckgaberecht. Senden Sie uns das Ger\u00e4t innerhalb dieser Frist in einwandfreiem Zustand zur\u00fcck, erstatten wir Ihnen den vollen Kaufpreis (abz\u00fcglich der Versandkosten).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-536f2542 elementor-widget elementor-widget-text-editor\" data-id=\"536f2542\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>*Diese Regelung gilt nur bei Bestellungen, die direkt \u00fcber die AMS abgewickelt werden. Unsere Vertriebspartner im In- und Ausland k\u00f6nnen davon abweichende Regelungen haben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b73d76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b73d76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90222d4\" data-id=\"90222d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6632e2 elementor-widget elementor-widget-menu-anchor\" data-id=\"d6632e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Einfuehrung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d72dde elementor-widget elementor-widget-heading\" data-id=\"1d72dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ausf\u00fchrliche Einf\u00fchrung zu den Kleinger\u00e4ten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c70452 elementor-widget elementor-widget-text-editor\" data-id=\"9c70452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMagnetfeldger\u00e4te? Wie nutzt man die \u00fcberhaupt?\n\nWenn Sie sich zun\u00e4chst ganz allgemein \u00fcber die Anwendung von den Kleinger\u00e4ten informieren m\u00f6chten, lesen Sie die ausf\u00fchrliche Einf\u00fchrung.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e5933f elementor-widget elementor-widget-menu-anchor\" data-id=\"1e5933f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Magnetfeldgeraete\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3997e0 elementor-widget elementor-widget-heading\" data-id=\"a3997e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Magnetfeldger\u00e4te f\u00fcr zu Hause<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-723fb3f elementor-widget elementor-widget-text-editor\" data-id=\"723fb3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Magnetfeldtherapieger\u00e4te k\u00f6nnen im Alltag in verschiedenen Situationen eingesetzt werden. So erfolgt die Anwendung beispielsweise zur\u00a0Anregung oder Entspannung\u00a0oder zur\u00a0Unterst\u00fctzung bei Konzentrationsschwierigkeiten.<\/p><p>Mit dem MEDICUR\u00aepro haben wir auch einen\u00a0&#8222;mobilen Schmerztherapeuten&#8220;.<\/p><p>Sie haben f\u00fcr den Heimbedarf die Auswahl zwischen sechs verschiedenen Magnetfeld-Kleinger\u00e4ten.<b><\/b><\/p><p><a href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/kleingeraete\/\" target=\"_blank\" rel=\"noopener\"><b>Kleinger\u00e4ten<\/b><\/a><\/p><p>Zus\u00e4tzlich bieten wir auch ein Gro\u00dfger\u00e4t f\u00fcr den Heimgebrauch an &#8211; Informationen hierzu finden Sie im Men\u00fcpunkt &#8222;Gro\u00dfger\u00e4t&#8220;.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/produkte\/heimbedarf\/grossgeraet\/\"><b>Gro\u00dfger\u00e4t<\/b><\/a><\/p><p>Zugegeben &#8211; es ist auf den ersten Blick gar nicht so leicht, die Unterschiede der einzelnen Ger\u00e4te zu erfassen und herauszufinden, welches sich f\u00fcr die eigenen Bed\u00fcrfnisse am besten eignet.<\/p><p>Aber keine Sorge &#8211; nachfolgend erhalten Sie einige Informationen zur allgemeinen Anwendung der Magnetfeldtherapie mit unseren Kleinger\u00e4ten. Sie erfahren auch, welche \u00fcbergeordneten Eigenschaften auf alle unsere Ger\u00e4te zutreffen.<\/p><p>F\u00fcr die individuellen Beschreibungen der einzelnen Ger\u00e4te und um konkret zu erfahren, worin sie sich voneinander unterscheiden, lesen Sie bitte die spezifischen Informationen auf der jeweiligen Produktseite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bb86a3 elementor-widget elementor-widget-text-editor\" data-id=\"2bb86a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine\u00a0\u00fcbersichtliche Auflistung der wichtigsten Eigenschaften und Unterschiede aller Kleinger\u00e4te finden Sie unter &#8222;Kleinger\u00e4te im Vergleich&#8220;. Hierzu sollten Sie jedoch schon die spezifischen Ger\u00e4tebeschreibungen gelesen haben, damit die in Kurzform gefassten Aussagen gut verst\u00e4ndlich f\u00fcr Sie sind.<\/p><p><a href=\"#Vergleich\"><b>Kleinger\u00e4te im Vergleich<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0173533 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0173533\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-097e342\" data-id=\"097e342\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b26c558 elementor-widget elementor-widget-menu-anchor\" data-id=\"b26c558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"anrufen\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c6f2b7 elementor-widget elementor-widget-heading\" data-id=\"4c6f2b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einfach anrufen!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad01800 elementor-widget elementor-widget-text-editor\" data-id=\"ad01800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vielleicht m\u00f6chten Sie es sich viel einfacher machen. Haben Sie bitte keine Scheu, uns anzurufen. Schildern Sie uns, warum Sie sich f\u00fcr ein Magnetfeldger\u00e4t interessieren oder stellen Sie uns Ihre Fragen zu den einzelnen Ger\u00e4ten. Wir helfen Ihnen, das oder die Ger\u00e4te zu finden, die f\u00fcr Sie in Frage kommen. Anschlie\u00dfend k\u00f6nnen Sie in Ruhe die dazugeh\u00f6rigen Produktbeschreibungen lesen.<\/p><p>Wir werden Sie niemals ungewollt kontaktieren oder Ihre Kontaktdaten an Dritte weitergeben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72e8b97 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"72e8b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-008ac36 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"008ac36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Advanced Medical Systems GmbH (AMS)<\/strong><br \/>Hauptstra\u00dfe 26<br \/>D-97990 Weikersheim<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddd7d95 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ddd7d95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Telefon: <a href=\"tel:+4979349934890\" target=\"_blank\" rel=\"noopener\"><b>+49 7934 993489-0<\/b><\/a><br \/>Telefax: +49 7934 993489-44<br \/>E-Mail: <a class=\"mail\" title=\"Opens window for sending email\" href=\"mailto:info@ams-ag.de\"><b>info@ams-ag.de<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1edd418 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1edd418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Gesch\u00e4ftszeiten:<br><\/b>Montag-Donnerstag 8:00-17:00 Uhr CET<br>Freitag 8:00-14:30 Uhr CET<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e59e89 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8e59e89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dbbe79 elementor-align-left elementor-widget__width-auto elementor-widget-tablet__width-inherit elementor-widget elementor-widget-button\" data-id=\"5dbbe79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/rueckruftermin\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00fcckruftermin<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aaff49 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"9aaff49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/info-material\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Info-Material bestellen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bc673b elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"1bc673b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/login-beantragen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Login beantragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e72d7ec elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"e72d7ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/kontakt\/newsletter-abonnieren\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Newsletter abonnieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5bc975 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5bc975\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9286b55\" data-id=\"9286b55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-540c20e elementor-widget elementor-widget-menu-anchor\" data-id=\"540c20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Anwendung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6d781b elementor-widget elementor-widget-heading\" data-id=\"a6d781b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendung der Kleinger\u00e4te<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59fba95 elementor-widget elementor-widget-text-editor\" data-id=\"59fba95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Anwendung der Magnetfeldtherapie mit unseren Ger\u00e4ten ist denkbar einfach. Gerade die Kleinger\u00e4te machen die Nutzung mit Hilfe der&nbsp;voreingestellten und w\u00e4hlbaren Programme sehr leicht.<\/p>\n<p>Schalten Sie das Ger\u00e4t einfach ein und legen es in die N\u00e4he Ihres K\u00f6rpers oder direkt auf Ihren K\u00f6rper &#8211; und schon befinden Sie sich im physiologischen Wirkungskreises des Magnetfeldes, das vom eingebauten Generator abgegeben wird. Sie k\u00f6nnen es nicht sehen oder h\u00f6ren. Sehr sensible Menschen sp\u00fcren manchmal etwas &#8211; das muss aber nicht sein. Auch wenn Sie das Magnetfeld des eingeschalteten Ger\u00e4tes nicht sofort ersp\u00fcren, erf\u00fcllt es dennoch seinen Zweck.<\/p>\n<p>Unsere Magnetfeldger\u00e4te erzeugen ein pulsierendes elektromagnetisches Feld in unterschiedlichen, w\u00e4hlbaren Frequenzen. Diese Felder k\u00f6nnen die Regulationsf\u00e4higkeit Ihres K\u00f6rpers unterst\u00fctzen. Was es genau mit der N\u00fctzlichkeit von pulsierenden elektromagnetischen Feldern auf sich hat, erfahren Sie im Men\u00fcpunkt&nbsp;&#8222;Magnetfeldtherapie und Bioinformative Medizin&#8220;.<\/p>\n<p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/\" rel=\"noopener\"><b>Magnetfeldtherapie und Bioinformative Medizin<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d37e9 elementor-widget elementor-widget-menu-anchor\" data-id=\"b1d37e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"wo\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d18d687 elementor-widget elementor-widget-heading\" data-id=\"d18d687\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wo soll das Ger\u00e4t getragen werden?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19cad4f elementor-widget elementor-widget-text-editor\" data-id=\"19cad4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je nach Gr\u00f6\u00dfe und wie es bequem ist, k\u00f6nnen Sie jedes tragbare Kleinger\u00e4t in die Hosen- oder Jackentasche stecken, mit einem Band um den Hals h\u00e4ngen oder einfach im Bett, auf dem Sofa oder im Lieblingssessel neben oder auf sich legen. Es gibt keinen Ort, an dem das Ger\u00e4t nicht angewandt werden darf.<\/p><p>Es ist nicht wichtig, wo genau das Ger\u00e4t platziert wird &#8211; die physiologische Reichweite ist gro\u00df genug f\u00fcr den K\u00f6rper.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43df881 elementor-widget elementor-widget-menu-anchor\" data-id=\"43df881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Frequenz\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6b8b1 elementor-widget elementor-widget-heading\" data-id=\"3e6b8b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Welche Frequenz soll ich w\u00e4hlen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59e1259 elementor-widget elementor-widget-text-editor\" data-id=\"59e1259\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jedes Ger\u00e4t bietet unterschiedlich viele Auswahlm\u00f6glichkeiten f\u00fcr voreingestellte Programme \/ Frequenzen.<\/p><p>Es gibt\u00a0keine indikationsbezogenen\u00a0Empfehlungen f\u00fcr die Nutzung der unterschiedlichen Frequenzen &#8211; denn\u00a0alle Frequenzen\u00a0k\u00f6nnen daf\u00fcr geeignet sein, die Regulation Ihres K\u00f6rpers positiv zu beeinflussen. Jedoch finden Sie Empfehlungen, f\u00fcr unterschiedliche Situationen ausgew\u00e4hlte Programme anzuwenden. Erfahrungsgem\u00e4\u00df k\u00f6nnen einigen Frequenzen bestimmte Eigenschaften zugeordnet werden. Hier einige Beispiele:<\/p><ul><li>ausgleichend (7,8 Hz)<\/li><li>anregend (33 \/ 20 Hz)<\/li><li>beruhigend (3,0 \/ 4,0 Hz)<\/li><li>konzentrationsf\u00f6rdernd (7,8 \/ 8,2 Hz)<\/li><li>entspannend (3,0 Hz \/ 1,2 Hz)<\/li><li>wohltuend bei Elektrosensibilit\u00e4t (1,2 Hz)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b683c7f elementor-widget elementor-widget-button\" data-id=\"b683c7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/kleingeraete\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kleinger\u00e4te im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcfe811 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcfe811\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7aebc4f\" data-id=\"7aebc4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c727d9 elementor-widget elementor-widget-menu-anchor\" data-id=\"2c727d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Substratuebertragung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b38a65c elementor-widget elementor-widget-heading\" data-id=\"b38a65c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Substrat\u00fcbertragung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b946d2 elementor-widget elementor-widget-text-editor\" data-id=\"0b946d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kann ich Informationen von Substraten wie z.B. hom\u00f6opathischer Mittel mit den Kleinger\u00e4ten \u00fcbertragen?<\/p><p>Ja. Jede elektromagnetische Welle ist in der Lage, Informationen zu transportieren und zu \u00fcbertragen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ae3210 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ae3210\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf0e19f\" data-id=\"cf0e19f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba8c769 elementor-widget elementor-widget-text-editor\" data-id=\"ba8c769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Damit Sie sich diese Eigenschaft zunutze machen k\u00f6nnen, verf\u00fcgt jedes unserer Kleinger\u00e4te \u00fcber einen Ampullenhalter, den Sie optional nutzen k\u00f6nnen. Er ist immer im Lieferumfang enthalten. Damit haben Sie die M\u00f6glichkeit, eine Ampulle mit der Information, die Sie \u00fcbertragen wollen, am Ger\u00e4t festzustecken.<\/p><p>Unabh\u00e4ngig davon, welche Frequenz \/ welches Programm des Ger\u00e4tes Sie w\u00e4hlen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ea2c1f\" data-id=\"8ea2c1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-667782a elementor-widget elementor-widget-image\" data-id=\"667782a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"309\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Metronom_solar_Ampullenhalter_Magnetfeldtherapie.jpg\" class=\"attachment-large size-large wp-image-5520\" alt=\"AMS Metronom solar Ampullenhalter\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Metronom_solar_Ampullenhalter_Magnetfeldtherapie.jpg 1024w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Metronom_solar_Ampullenhalter_Magnetfeldtherapie-300x116.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Metronom_solar_Ampullenhalter_Magnetfeldtherapie-768x296.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad5ff48 elementor-widget elementor-widget-text-editor\" data-id=\"ad5ff48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jede Frequenz ist Tr\u00e4gerwelle und kann zum Einschwingen \/ \u00dcbertragen eingesetzt werden.<\/p><p>Was es genau mit dem Einschwingen von Substraten und Informationen auf sich hat, lesen Sie im Men\u00fcpunkt &#8222;Substrat\u00fcbertragung&#8220;.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/substratuebertragung\/\"><b>Substrat\u00fcbertragung<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dcfe56 elementor-widget elementor-widget-button\" data-id=\"7dcfe56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/kleingeraete\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kleinger\u00e4te im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-054e00e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"054e00e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd2d515\" data-id=\"bd2d515\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-685ede1 elementor-widget elementor-widget-menu-anchor\" data-id=\"685ede1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Eigenschaften\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3978c elementor-widget elementor-widget-heading\" data-id=\"7c3978c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eigenschaften der Ger\u00e4te von Dr. Ludwig<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e327a2 elementor-widget elementor-widget-text-editor\" data-id=\"7e327a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle unsere Kleinger\u00e4te sind mit der von Dr. Ludwig entwickelten Technologie ausgestattet.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/ueber-ams\/ams-dr-ludwig\/\"><b>Dr. Ludwig<\/b><\/a><\/p><p>Ihm war es besonders wichtig, mit seinen Ger\u00e4ten ein Magnetfeld zu erzeugen, das der ungest\u00f6rten Natur nachempfunden ist &#8211; deshalb gilt f\u00fcr alle von Dr. Ludwig und in seinem Institut (weiter)entwickelten Magnetfeldger\u00e4te:<\/p><ul><li>Erzeugung bzw. m\u00f6gliche Wahl des Hauptwertes des\u00a0Schumannfrequenzspektrums (7,8 Hz)<\/li><li>Erzeugung der\u00a0Geomagnetfrequenzen<\/li><li>Erzeugung der\u00a0Solarfrequenzen\u00a0(bis auf das MEDISEND\u00ae und das MEDISEND\u00aeprotect, bei denen man aufgrund der Geh\u00e4usegr\u00f6\u00dfe auf den Einbau des Solarfrequenzgenerators verzichtete)<\/li><\/ul><p>Die genaue Beschreibung f\u00fcr Schumann-, Geomagnet- und Solarfrequenzen finden Sie im Men\u00fcpunkt &#8222;Umweltsignale&#8220;.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/umweltsignale\/\"><b>Umweltsignale<\/b><\/a><\/p><p>Alle Ger\u00e4te erzeugen ein Signal, dessen Impulsform und Magnetfeldst\u00e4rke optimal auf den K\u00f6rper abgestimmt ist. Lesen Sie hierzu mehr im Men\u00fcpunkt &#8222;Qualit\u00e4tsmerkmale&#8220;.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/magnetfeldtherapie-und-bioinformative-medizin\/qualitaetsmerkmale\/\"><b>Qualit\u00e4tsmerkmale<\/b><\/a><\/p><p>Die von Dr. Ludwig entwickelten Ger\u00e4te erkennen Sie am Pfeilsymbol.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/pfeilsymbol\/\"><b>Pfeilsymbol<\/b><\/a><\/p><p>Das erste von Dr. Ludwig erschaffene Ger\u00e4t war vor \u00fcber 40 Jahren das heutige MEDISEND\u00ae &#8211; damals nat\u00fcrlich noch in einer anderen Ausf\u00fchrung.<\/p><p>Wie und warum Dr. Ludwig sein erstes Magnetfeldger\u00e4t baute und wie er nach und nach die unterschiedlichen Ger\u00e4te entwickelte und erweiterte lesen Sie im Men\u00fcpunkt &#8222;Geschichte unserer Ger\u00e4te&#8220;.<b><\/b><\/p><p><a href=\"https:\/\/www.ams-ag.de\/grundlagen-magnetfeldtherapie\/geschichte-unserer-geraete\/\"><b>Geschichte unserer Ger\u00e4te<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4368c13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4368c13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d507b9b\" data-id=\"d507b9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d937208 elementor-widget elementor-widget-menu-anchor\" data-id=\"d937208\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Vergleich\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58f4d9b5 elementor-widget elementor-widget-heading\" data-id=\"58f4d9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Kleinger\u00e4te im Vergleich zueinander<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe3885 elementor-widget elementor-widget-image\" data-id=\"bfe3885\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"474\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-1.jpg\" class=\"attachment-large size-large wp-image-3996\" alt=\"Tabelle Kleinger\u00e4te Eigenschaften\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-1.jpg 1024w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-1-300x178.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-1-768x455.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-204d29e elementor-widget elementor-widget-image\" data-id=\"204d29e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"477\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-2.jpg\" class=\"attachment-large size-large wp-image-3997\" alt=\"Tabelle Kleinger\u00e4te Eigenschaften\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-2.jpg 1024w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-2-300x179.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Eigenschaften_22_Preise-2-768x458.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9fa560 elementor-widget elementor-widget-image\" data-id=\"b9fa560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"543\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Vergleich_22_Preise.jpg\" class=\"attachment-large size-large wp-image-3998\" alt=\"Tabelle Kleinger\u00e4te Vergleich\" srcset=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Vergleich_22_Preise.jpg 1024w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Vergleich_22_Preise-300x204.jpg 300w, https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/csm_AMS_Tabelle_Kleingeraete_Vergleich_22_Preise-768x521.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b085115 elementor-widget elementor-widget-button\" data-id=\"b085115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/kleingeraete\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kleinger\u00e4te im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a8cb05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a8cb05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c14f8cf\" data-id=\"c14f8cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e7b739 elementor-widget elementor-widget-menu-anchor\" data-id=\"3e7b739\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Pfeil\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aac9d7f elementor-widget elementor-widget-heading\" data-id=\"aac9d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pfeilsymbol<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f9dbcc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9dbcc5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-76d7036\" data-id=\"76d7036\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13d2cf3 elementor-widget elementor-widget-text-editor\" data-id=\"13d2cf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie von Dr. Ludwig\u00ae entwickelten Ger\u00e4te erkennen Sie an dem Pfeilsymbol. Dieses Symbol steht f\u00fcr die Erzeugung eines elektromagnetischen Biofeldes, das der ungest\u00f6rten Natur nachempfunden ist.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fac06f3\" data-id=\"fac06f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-449f235 elementor-widget elementor-widget-image\" data-id=\"449f235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/05\/image-32.jpeg\" class=\"attachment-medium size-medium wp-image-1730\" alt=\"Pfeilsymbol von Dr. Ludwig\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-833b283 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"833b283\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc96c62\" data-id=\"fc96c62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-badc968 elementor-widget elementor-widget-menu-anchor\" data-id=\"badc968\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Downloads\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a4f7cc elementor-widget elementor-widget-heading\" data-id=\"1a4f7cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Downloads<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b06b1b elementor-widget elementor-widget-text-editor\" data-id=\"7b06b1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hier k\u00f6nnen Sie die Tabellen als PDF-Dokument herunterladen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-925a3e9 elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"925a3e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1531\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1531\" aria-expanded=\"false\">Deutsch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1532\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1532\" aria-expanded=\"false\">Englisch<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1531\" aria-expanded=\"false\">Deutsch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1531\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1531\" tabindex=\"0\" hidden=\"false\"><ul><li><b><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/03\/Vorteile-und-Unterschiede-der-Kleingeraete-der-AMS-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\">Vorteile und Unterschiede der Kleinger\u00e4te der AMS auf Deutsch<\/a><\/b><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/09\/AMS_Tabelle_Kleingeraete_Vergleich_22_Preise.pdf\" target=\"_blank\" rel=\"noopener\"><b>Tabelle Eigenschaften AMS Kleinger\u00e4te (504 KB) de<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1532\" aria-expanded=\"false\">Englisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1532\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1532\" tabindex=\"0\" hidden=\"hidden\"><ul>\n \t<li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS_chart_small_devices_properties_English.pdf\" target=\"_blank\" rel=\"noopener\"><b>AMS chart small devices properties (96 KB) en<\/b><\/a><\/li>\n \t<li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS_chart_small_devices_in_comparison_English.pdf\" target=\"_blank\" rel=\"noopener\"><b>AMS chart small devices in comparison (88 KB) en<\/b><\/a><\/li>\n<\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f351e12 elementor-widget elementor-widget-menu-anchor\" data-id=\"f351e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Prospekte\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc255ee elementor-widget elementor-widget-heading\" data-id=\"fc255ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prospekte Kleinger\u00e4te<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d0577 elementor-widget elementor-widget-text-editor\" data-id=\"b1d0577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nachfolgend k\u00f6nnen Sie alle&nbsp;Prospekte unserer Kleinger\u00e4te herunterladen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a65fc9 elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"2a65fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4441\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4441\" aria-expanded=\"false\">Deutsch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4442\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4442\" aria-expanded=\"false\">Englisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4443\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4443\" aria-expanded=\"false\">Portugiesisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4444\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4444\" aria-expanded=\"false\">Spanisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4445\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4445\" aria-expanded=\"false\">T\u00fcrkisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4446\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4446\" aria-expanded=\"false\">Italienisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4447\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4447\" aria-expanded=\"false\">Japanisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4448\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4448\" aria-expanded=\"false\">Franz\u00f6sisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-4449\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4449\" aria-expanded=\"false\">Rum\u00e4nisch<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-44410\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-44410\" aria-expanded=\"false\">Ungarisch<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-4441\" aria-expanded=\"false\">Deutsch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4441\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4441\" tabindex=\"0\" hidden=\"false\"><ul><li><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/02\/MEDISEND\u00ae-Prospekt-Stand-01-2026-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\"><strong>MEDISEND\u00ae Prospekt, Stand 01-2026, auf Deutsch<\/strong><\/a><\/li><li><b><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/02\/MEDISEND\u00aeprotect-Prospekt-Stand-01-2026-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\">MEDISEND\u00aeprotect Prospekt, Stand 01-2026, auf Deutsch<\/a><\/b><\/li><li><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/04\/MEDICUR\u00aepro-Prospekt-Stand-05-2026-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDICUR\u00aepro Prospekt, Stand 05-2026, auf Deutsch<\/b><\/a><\/li><li><b><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/02\/MEDICUR\u00aecolor-Prospekt-Stand-01-2026-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\">MEDICUR\u00aecolor Prospekt, Stand 01-2026, auf Deutsch<\/a><\/b><\/li><li><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/02\/METRONOM-solar-Prospekt-Stand-01-2026-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\"><b>METRONOM solar Prospekt, Stand 01-2026, auf Deutsch<\/b><\/a><\/li><li><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2026\/02\/METRONOM-C-Prospekt-Stand-01-2026-auf-Deutsch.pdf\" target=\"_blank\" rel=\"noopener\"><b>METRONOM C Prospekt, Stand 01-2026, auf Deutsch<\/b><\/a><\/li><li><b><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/04\/AMS-Einfuehrung-in-die-Magnetfeldtherapie-und-Bioresonanz.pdf\" target=\"_blank\" rel=\"noopener\">AMS Einf\u00fchrung in die Magnetfeldtherapie und Bioresonanz<\/a><\/b><br \/>Mittelteil aller Prospekte<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4442\" aria-expanded=\"false\">Englisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4442\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4442\" tabindex=\"0\" hidden=\"hidden\"><p>The middle part can be downloaded separately with the file <b>&#8222;Introduction to Magnetic Field Therapy and Bioresonance&#8220;<\/b>:<\/p><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/Magnetic-field-therapy-web.pdf\" target=\"_blank\" rel=\"noopener\"><b>Introduction Magnetic field therapy and Bioresonance (734 KB) en<\/b><\/a><br \/>middle part of the printed brochures<\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/Medisend-eng-o-M-web.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDISEND\u00ae brochure (496 KB) en<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/Medisend-protect-eng-o-M-web.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDISEND\u00aeprotect brochure (277 KB) en<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/Medicur-pro-eng-o-M-web.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDICUR\u00aepro brochure (565 KB) en<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/Medicur-color-eng-o-M-web.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDICUR\u00aecolor brochure (277 KB) en<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/Metronom-solar-eng-o-M-web.pdf\" target=\"_blank\" rel=\"noopener\"><b>METRONOM solar brochure (496 KB) en<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS-METRONOM-C-brochure-without-middle-section.pdf\" target=\"_blank\" rel=\"noopener\"><b>METRONOM C brochure (1.0 MB) en<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4443\" aria-expanded=\"false\">Portugiesisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4443\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4443\" tabindex=\"0\" hidden=\"hidden\"><p>\u00c9 poss\u00edvel baixar a parte interna separadamente abaixo com o arquivo <b>&#8222;Introdu\u00e7\u00e3o \u00e0 Terapia de Campo Magn\u00e9tico e Bioreson\u00e2ncia&#8220;<\/b>:<\/p><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS-Doppelseiter-Bioinformative-Medizin-Portugiesisch.pdf\" target=\"_blank\" rel=\"noopener\"><b>Introdu\u00e7\u00e3o Terapia de campo magn\u00e9tico e Biorresson\u00e2ncia (737 KB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS-portugues-MEDISEND-prospecto.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDISEND\u00ae prospecto (436 KB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_portugues_MEDISEND_manual.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manual MEDISEND\u00ae (0.9 MB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS-portugues-MEDISEND-protect-prospecto.pdf\" target=\"_blank\" rel=\"noopener\"><b>MEDISEND\u00aeprotect prospecto (617 KB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_portugues_MEDISEND_protect_manual.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manual MEDISEND\u00aeprotect (574 KB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/11\/AMS-portugues-METRONOM-C-prospecto.pdf\" target=\"_blank\" rel=\"noopener\"><b>METRONOM C prospecto (517 KB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/METRONOM_C_manual_de_uso_Portugiesisch.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manual METRONOM C (1.0 MB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_portugues_A_Medicina_Bioinformativa_em_uma_clinica_de_naturopatia.pdf\" target=\"_blank\" rel=\"noopener\"><b>A Medicina Bioinformativa em uma cl\u00ednica de naturopatia (811 KB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_portugues_Palestra_-_Simplesmente_otimas_vibracoes.pdf\" target=\"_blank\" rel=\"noopener\"><b>Palestra &#8211; Simplesmente \u00f3timas vibra\u00e7\u00f5es (3.0 MB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_portugues_Palestra_-_Electrosmog__o_perigo_invisivel.pdf\" target=\"_blank\" rel=\"noopener\"><b>Palestra &#8211; Electrosmog, o perigo invis\u00edvel (3.5 MB) pt<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_portugues_O_Eletrosmog_prejudica_nossa_saude.pdf\" target=\"_blank\" rel=\"noopener\"><b>O Eletrosmog prejudica nossa sa\u00fade (112 KB) pt<\/b><\/a><\/li><li><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2024\/07\/Preisliste-fuer-Brasilien-in-BRL-auf-Portugiesisch-Stand-2024.pdf\" target=\"_blank\" rel=\"noopener\"><b>Preisliste f\u00fcr Brasilien in BRL auf Portugiesisch, Stand 2024 (514 kB)<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4444\" aria-expanded=\"false\">Spanisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4444\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4444\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_espanol_Introduccion_Terapia_campo_magnetico.pdf\" target=\"_blank\" rel=\"noopener\"><b>Introducci\u00f3n Terapia campo Magn\u00e9tico y Bioresonancia (700 KB) es<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_espanol_Descripcion_equipos_AMS_general.pdf\" target=\"_blank\" rel=\"noopener\"><b>Descripci\u00f3n de los equipos de la AMS en general (524 KB) es<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_espanol_Campo_Magnetico_y_Medicina_Bioinformativa.pdf\"><b>Campo Magn\u00e9tico y Medicina Bioinformativa (97 KB) es<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4445\" aria-expanded=\"false\">T\u00fcrkisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4445\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4445\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_tuerk_Info_Bioninformative_Medizin.pdf\" target=\"_blank\" rel=\"noopener\"><b>Bilgi Biyoinformatik T\u0131p (1.1 MB) tr<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_tuerk_MEDISEND_Prospekt.pdf\" target=\"_blank\" rel=\"noopener\"><b>Bro\u015f\u00fcr MEDISEND\u00ae (1.5 MB) tr<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_tuerk_MEDISEND_Anleitung.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manuel MEDISEND\u00ae (365 KB) tr<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4446\" aria-expanded=\"false\">Italienisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4446\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4446\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_italiano_MEDISEND_prospetto.pdf\" target=\"_blank\" rel=\"noopener\"><b>Brochure MEDISEND\u00ae (281 KB) it<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_italiano_MEDISEND_manuale.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manuale MEDISEND\u00ae (4.2 MB) it<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_italiano_MEDISEND_protect_prospetto.pdf\" target=\"_blank\" rel=\"noopener\"><b>Brochure MEDISEND\u00aeprotect (323 KB) it<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_italiano_METRONOM_solar_manuale.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manuale METRONOM solar (384 KB) it<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4447\" aria-expanded=\"false\">Japanisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4447\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4447\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"http:\/\/www.ams-ag.de\/wp-content\/uploads\/2025\/07\/Handy-Test-Medisend-auf-Japanisch.pdf\" target=\"_blank\" rel=\"noopener\"><b>Handy Test Medisend auf Japanisch<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"8\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4448\" aria-expanded=\"false\">Franz\u00f6sisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4448\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4448\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_francais_Magnetotherapie_Ludwig.pdf\" target=\"_blank\" rel=\"noopener\"><b>Manuale METRONOM solar (384 KB) fr<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_francais_Rapport_Apoplexie.pdf\" target=\"_blank\" rel=\"noopener\"><b>Rapport apoplexie (509 KB) fr<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"9\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-4449\" aria-expanded=\"false\">Rum\u00e4nisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4449\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-4449\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_romanian_Medicina_Bioinformativa.pdf\" target=\"_blank\" rel=\"noopener\"><b>Bioinformatic Medicina (352 KB) ro<\/b><\/a><\/li><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_romanian_Brochure_Magnetic_Field.pdf\" target=\"_blank\" rel=\"noopener\"><b>Terapia c\u00e2mp electromagnetic (2.0 MB) ro<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"10\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-44410\" aria-expanded=\"false\">Ungarisch<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-44410\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-44410\" tabindex=\"0\" hidden=\"hidden\"><ul><li><a href=\"https:\/\/www.ams-ag.de\/wp-content\/uploads\/2023\/12\/AMS_hungarian_MEDICUR_Anleitung.pdf\" target=\"_blank\" rel=\"noopener\"><b>K\u00e9zi MEDICUR\u00ae (415 KB) hu<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-048e581 elementor-widget elementor-widget-button\" data-id=\"048e581\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/ams-onlineshop.de\/produkt-kategorie\/heimbedarf\/kleingeraete\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kleinger\u00e4te im Shop<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-847648e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"847648e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ffdb23\" data-id=\"1ffdb23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f24c56d elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f24c56d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ams-ag.de\/es\/produkte\/heimbedarf\/kleingeraete\/medisend\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MEDISEND\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00dcberall dabei Kleinger\u00e4te f\u00fcr den Heimbedarf Sie suchen ein kleines und handliches Magnetfeldger\u00e4t\u00a0f\u00fcr zu Hause und unterwegs? Dann sind Sie auf dieser Seite genau richtig. Finden Sie hier Ihr Magnetfeldger\u00e4t, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4153,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pmpro_default_level":"","footnotes":""},"class_list":["post-3995","page","type-page","status-publish","hentry","pmpro-has-access"],"_links":{"self":[{"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/pages\/3995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/comments?post=3995"}],"version-history":[{"count":147,"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/pages\/3995\/revisions"}],"predecessor-version":[{"id":20084,"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/pages\/3995\/revisions\/20084"}],"up":[{"embeddable":true,"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/pages\/4153"}],"wp:attachment":[{"href":"https:\/\/www.ams-ag.de\/es\/wp-json\/wp\/v2\/media?parent=3995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}